{"id":138,"count":2,"description":"","link":"https:\/\/d-actual.id\/index.php\/tag\/intan\/","name":"Intan","slug":"intan","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Intan Arsip - d-actual.id<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/d-actual.id\/index.php\/tag\/intan\/\" \/>\n<meta property=\"og:locale\" content=\"id_ID\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Intan Arsip - d-actual.id\" \/>\n<meta property=\"og:url\" content=\"https:\/\/d-actual.id\/index.php\/tag\/intan\/\" \/>\n<meta property=\"og:site_name\" content=\"d-actual.id\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/d-actual.id\\\/index.php\\\/tag\\\/intan\\\/\",\"url\":\"https:\\\/\\\/d-actual.id\\\/index.php\\\/tag\\\/intan\\\/\",\"name\":\"Intan Arsip - d-actual.id\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/d-actual.id\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/d-actual.id\\\/index.php\\\/tag\\\/intan\\\/#breadcrumb\"},\"inLanguage\":\"id\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/d-actual.id\\\/index.php\\\/tag\\\/intan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Beranda\",\"item\":\"https:\\\/\\\/d-actual.id\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Intan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/d-actual.id\\\/#website\",\"url\":\"https:\\\/\\\/d-actual.id\\\/\",\"name\":\"d-actual.id\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/d-actual.id\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/d-actual.id\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"id\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/d-actual.id\\\/#organization\",\"name\":\"d-actual.id\",\"url\":\"https:\\\/\\\/d-actual.id\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"id\",\"@id\":\"https:\\\/\\\/d-actual.id\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/d-actual.id\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/d-actual.id\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo.png\",\"width\":289,\"height\":63,\"caption\":\"d-actual.id\"},\"image\":{\"@id\":\"https:\\\/\\\/d-actual.id\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Intan Arsip - d-actual.id","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/d-actual.id\/index.php\/tag\/intan\/","og_locale":"id_ID","og_type":"article","og_title":"Intan Arsip - d-actual.id","og_url":"https:\/\/d-actual.id\/index.php\/tag\/intan\/","og_site_name":"d-actual.id","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/d-actual.id\/index.php\/tag\/intan\/","url":"https:\/\/d-actual.id\/index.php\/tag\/intan\/","name":"Intan Arsip - d-actual.id","isPartOf":{"@id":"https:\/\/d-actual.id\/#website"},"breadcrumb":{"@id":"https:\/\/d-actual.id\/index.php\/tag\/intan\/#breadcrumb"},"inLanguage":"id"},{"@type":"BreadcrumbList","@id":"https:\/\/d-actual.id\/index.php\/tag\/intan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Beranda","item":"https:\/\/d-actual.id\/"},{"@type":"ListItem","position":2,"name":"Intan"}]},{"@type":"WebSite","@id":"https:\/\/d-actual.id\/#website","url":"https:\/\/d-actual.id\/","name":"d-actual.id","description":"","publisher":{"@id":"https:\/\/d-actual.id\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/d-actual.id\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"id"},{"@type":"Organization","@id":"https:\/\/d-actual.id\/#organization","name":"d-actual.id","url":"https:\/\/d-actual.id\/","logo":{"@type":"ImageObject","inLanguage":"id","@id":"https:\/\/d-actual.id\/#\/schema\/logo\/image\/","url":"https:\/\/d-actual.id\/wp-content\/uploads\/2022\/01\/logo.png","contentUrl":"https:\/\/d-actual.id\/wp-content\/uploads\/2022\/01\/logo.png","width":289,"height":63,"caption":"d-actual.id"},"image":{"@id":"https:\/\/d-actual.id\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/d-actual.id\/index.php\/wp-json\/wp\/v2\/tags\/138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/d-actual.id\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/d-actual.id\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/d-actual.id\/index.php\/wp-json\/wp\/v2\/posts?tags=138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}